{"id":130182,"date":"2026-04-27T10:43:18","date_gmt":"2026-04-27T15:43:18","guid":{"rendered":"https:\/\/www.ciencuadras.com\/blog\/?page_id=130182"},"modified":"2026-04-27T10:43:20","modified_gmt":"2026-04-27T15:43:20","slug":"guia-de-barrio-la-doctora-sabaneta-antioquia","status":"publish","type":"page","link":"https:\/\/www.ciencuadras.com\/blog\/guia-de-barrio-la-doctora-sabaneta-antioquia","title":{"rendered":"La Doctora, un refugio campestre y exclusivo en Sabaneta"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"130182\" class=\"elementor elementor-130182\" data-elementor-post-type=\"page\">\n\t\t\t\t\n<div class=\"elementor-element elementor-element-c8e79f8 e-con-full e-flex e-con e-parent\" data-id=\"c8e79f8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38eb1ed elementor-widget elementor-widget-image\" data-id=\"38eb1ed\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/www.ciencuadras.com\/blog\/wp-content\/uploads\/2026\/03\/1200x630_La-Doctora-1024x536.jpg\" class=\"attachment-large size-large wp-image-130184\" alt=\"\" srcset=\"https:\/\/www.ciencuadras.com\/blog\/wp-content\/uploads\/2026\/03\/1200x630_La-Doctora-1024x536.jpg 1024w, https:\/\/www.ciencuadras.com\/blog\/wp-content\/uploads\/2026\/03\/1200x630_La-Doctora-300x157.jpg 300w, https:\/\/www.ciencuadras.com\/blog\/wp-content\/uploads\/2026\/03\/1200x630_La-Doctora-768x402.jpg 768w, https:\/\/www.ciencuadras.com\/blog\/wp-content\/uploads\/2026\/03\/1200x630_La-Doctora.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4994f67 e-flex e-con-boxed e-con e-parent\" data-id=\"4994f67\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-db81695 e-con-full e-flex e-con e-child\" data-id=\"db81695\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a65307a e-con-full e-flex e-con e-child\" data-id=\"a65307a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1470059 elementor-widget elementor-widget-heading\" data-id=\"1470059\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La Doctora en cifras<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a14ced e-grid e-con-full e-con e-child\" data-id=\"5a14ced\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3d90f1e e-grid e-con-full e-con e-child\" data-id=\"3d90f1e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d7104d elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"8d7104d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">$643.177.882<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c87f41 elementor-widget elementor-widget-text-editor\" data-id=\"5c87f41\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Precio promedio venta<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c1e595e e-grid e-con-full e-con e-child\" data-id=\"c1e595e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02f37ed elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"02f37ed\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">$8.513.552<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f36e5aa elementor-widget elementor-widget-text-editor\" data-id=\"f36e5aa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Precio promedio m2<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a84e289 e-grid e-con-full e-con e-child\" data-id=\"a84e289\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75d15d7 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"75d15d7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b6f6b1 elementor-widget elementor-widget-text-editor\" data-id=\"3b6f6b1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Estrato<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d781d7d elementor-widget elementor-widget-text-editor\" data-id=\"d781d7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La Doctora es un sector tradicionalmente rural que ha evolucionado hacia una de las zonas residenciales m\u00e1s exclusivas del sur del Valle de Aburr\u00e1. Ubicado en la zona alta de Sabaneta, este barrio se caracteriza por una atm\u00f3sfera campestre con una oferta inmobiliaria dominada por casas en parcelaciones independientes y modernos edificios de apartamentos con vistas panor\u00e1micas.\u00a0<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd3e61b e-con-full e-flex e-con e-child\" data-id=\"bd3e61b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d62f36 elementor-widget elementor-widget-heading\" data-id=\"1d62f36\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfPor qu\u00e9 elegir La Doctora?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e675f51 elementor-widget elementor-widget-text-editor\" data-id=\"e675f51\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>El sector cuenta con todo lo necesario para disfrutar de una buena calidad de vida. Estas son las ventajas de vivir en La Doctora:<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c017709 e-grid e-con-full e-con e-child\" data-id=\"c017709\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9cc9af7 e-grid e-con-full e-con e-child\" data-id=\"9cc9af7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d7d82c elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"3d7d82c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Espacios verdes<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-352d06d elementor-widget elementor-widget-text-editor\" data-id=\"352d06d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El barrio es un pulm\u00f3n natural para Sabaneta. Su cercan\u00eda a la reserva ecol\u00f3gica <\/span><b>La Romera<\/b><span style=\"font-weight: 400;\"> permite a los residentes acceder a senderos para senderismo y avistamiento de aves. La abundancia de vegetaci\u00f3n nativa en los antejardines y zonas comunes garantiza un clima m\u00e1s fresco y una baja contaminaci\u00f3n auditiva.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4378a48 e-grid e-con-full e-con e-child\" data-id=\"4378a48\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c51640 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"0c51640\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Oferta comercial<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6fba5c elementor-widget elementor-widget-text-editor\" data-id=\"a6fba5c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">A unos minutos se encuentra el <\/span><b>Centro Comercial Mayorca Mega Plaza<\/b><span style=\"font-weight: 400;\">, uno de los m\u00e1s grandes de la regi\u00f3n. Adem\u00e1s, en la base del sector se localizan mercados independientes, farmacias y una variada oferta gastron\u00f3mica local que incluye restaurantes tradicionales y caf\u00e9s de especialidad.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e907f1 e-grid e-con-full e-con e-child\" data-id=\"6e907f1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9bf3001 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"9bf3001\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">V\u00edas de acceso<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e44f32 elementor-widget elementor-widget-text-editor\" data-id=\"3e44f32\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Su eje principal es la <\/span><b>Avenida La Doctora<\/b><span style=\"font-weight: 400;\">, que conecta directamente con la zona urbana de Sabaneta. La proximidad a la <\/span><b>Avenida Regional<\/b><span style=\"font-weight: 400;\"> y la <\/span><b>Autopista Sur<\/b><span style=\"font-weight: 400;\"> facilita el desplazamiento hacia Medell\u00edn y otros municipios del sur, como Envigado e Itag\u00fc\u00ed.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8054433 e-grid e-con-full e-con e-child\" data-id=\"8054433\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc5322c elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"dc5322c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Educaci\u00f3n <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69d51df elementor-widget elementor-widget-text-editor\" data-id=\"69d51df\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El sector destaca por su cercan\u00eda a instituciones de alto nivel como el <\/span><b>Colegio El Carmelo<\/b><span style=\"font-weight: 400;\"> y la sede principal de la <\/span><b>Universidad CEIPA<\/b><span style=\"font-weight: 400;\">. Esto lo convierte en un punto estrat\u00e9gico para familias con hijos en edad escolar y para la comunidad acad\u00e9mica de posgrados.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af63541 e-con-full e-flex e-con e-child\" data-id=\"af63541\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c795e3 elementor-widget elementor-widget-heading\" data-id=\"6c795e3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><h2 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\" style=\", sans-serif;font-weight: 700;line-height: 1px\">Ubicaci\u00f3n privilegiada<span style=\"font-family: Montserrat, sans-serif\"><\/span><\/h2><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81e48d8 elementor-widget elementor-widget-text-editor\" data-id=\"81e48d8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La Doctora se localiza en la zona suroriental del municipio de Sabaneta (\u00e1rea metropolitana de Medell\u00edn). Limita hacia el occidente con el casco urbano municipal y hacia el oriente con la cordillera que conduce a la reserva La Romera. Su elevaci\u00f3n sobre el nivel del valle le otorga una ventaja clim\u00e1tica y visual, permitiendo ver toda el \u00e1rea metropolitana, mientras se mantiene conectado con el centro administrativo y el Parque de Sabaneta a menos de 10 minutos en veh\u00edculo.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d246008 e-con-full e-flex e-con e-child\" data-id=\"d246008\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8fde598 elementor-widget elementor-widget-heading\" data-id=\"8fde598\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inmuebles en La Doctora<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14d85ec e-con-full e-flex e-con e-child\" data-id=\"14d85ec\" data-element_type=\"container\">\n\t\t\n\t\t<div class=\"elementor-element elementor-element-c7f6307 elementor-widget elementor-widget-slider-inmuebles-ciencuadras\" data-id=\"c7f6307\" data-element_type=\"widget\" data-settings=\"{&quot;select_tipo_transaccion&quot;:&quot;venta&quot;}\" data-widget_type=\"slider-inmuebles-ciencuadras.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t           <!-- Swiper-->\n            <div class=\"container-swiper container-id-c7f6307\" >\n                    <div class=\"swiper-button-prev prev-swiper-id-c7f6307\"><\/div>\n                        <div class=\"swiper mySwiper swiper-id-c7f6307\">\n                         <div class=\"swiper-wrapper\">\n                                <div data-history=\"0\" class=\"swiper-slide\" >\n                            <a class=\"card\"  href=\"\/inmueble\/apartamento-en-venta-en-lagos-de-la-doctora-sabaneta-3103695\" target=\"_blank\">\n                                <div class=\"card-image\">\n                                    <img decoding=\"async\" class=\"img-inmueble\"  \n                                        src=\"https:\/\/www-img-cc.s3.amazonaws.com\/inmuebles\/images\/3103695\/daa176426532768_plana.jpeg\"\n                                        alt=\"Apartamento\"\n                                        onerror=\"this.src='https:\/\/www.ciencuadras.com\/sources\/images\/result\/no-photo-property.png'\"\n                                    \/>\n                                <\/div>\n                                <div class=\"card-info\">\n                                    <div class=\"card-price\">\n                                        <span>Valor de compra: <\/span>                                        <br \/>\n                                        <span class=\"card-price-big\">$900.000.000 \n                                        <\/span>\n                                    <\/div>\n                                    <div class=\"card-location\">\n                                        Apartamento en Venta                                    <\/div>\n                                    <div class=\"card-direction\">\n                                        <div class=\"card-target\">\n                                            <em class=\"fas fa-map-marker-alt\"><\/em>\n                                            <span class=\"city\"> Sabaneta<\/span>\n                                            <span>&nbsp;\/&nbsp;<\/span>\n                                            <span class=\"neighborhood\"> Lagos De La Doctora<\/span>\n                                        <\/div>\n                                    <\/div>\n                                    <div class=\"specs\">\n                                        <div class=\"specs-data area\"><span class=\"span-data\">168 m2<\/span><\/div>\n                                        <div class=\"specs-data rooms\"><span class=\"span-data\">Habit. 4<\/span><\/div><div class=\"specs-data baths\"><span class=\"span-data\">Ba\u00f1os 3<\/span><\/div><div class=\"specs-data garages\"><span class=\"span-data\">Garaje 2<\/span><\/div>                                        \n                                        \n                                        \n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        <\/div>\n                    \n                   \n\t\t\t\n                                <div data-history=\"1\" class=\"swiper-slide\" >\n                            <a class=\"card\"  href=\"\/inmueble\/apartamento-en-venta-en-otros-sabaneta-3599282\" target=\"_blank\">\n                                <div class=\"card-image\">\n                                    <img decoding=\"async\" class=\"img-inmueble\"  \n                                        src=\"https:\/\/www.ciencuadras.com\/sources\/images\/result\/no-photo-property.jpg\"\n                                        alt=\"Apartamento\"\n                                        onerror=\"this.src='https:\/\/www.ciencuadras.com\/sources\/images\/result\/no-photo-property.png'\"\n                                    \/>\n                                <\/div>\n                                <div class=\"card-info\">\n                                    <div class=\"card-price\">\n                                        <span>Valor de compra: <\/span>                                        <br \/>\n                                        <span class=\"card-price-big\">$270.000.000 \n                                        <\/span>\n                                    <\/div>\n                                    <div class=\"card-location\">\n                                        Apartamento en Venta                                    <\/div>\n                                    <div class=\"card-direction\">\n                                        <div class=\"card-target\">\n                                            <em class=\"fas fa-map-marker-alt\"><\/em>\n                                            <span class=\"city\"> Sabaneta<\/span>\n                                            <span>&nbsp;\/&nbsp;<\/span>\n                                            <span class=\"neighborhood\"> Otros<\/span>\n                                        <\/div>\n                                    <\/div>\n                                    <div class=\"specs\">\n                                        <div class=\"specs-data area\"><span class=\"span-data\">50 m2<\/span><\/div>\n                                        <div class=\"specs-data rooms\"><span class=\"span-data\">Habit. 3<\/span><\/div><div class=\"specs-data baths\"><span class=\"span-data\">Ba\u00f1os 2<\/span><\/div>                                        \n                                        \n                                        \n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        <\/div>\n                    \n                   \n\t\t\t\n                                <div data-history=\"2\" class=\"swiper-slide\" >\n                            <a class=\"card\"  href=\"\/inmueble\/apartamento-en-venta-en-lagos-de-la-doctora-sabaneta-3558291\" target=\"_blank\">\n                                <div class=\"card-image\">\n                                    <img decoding=\"async\" class=\"img-inmueble\"  \n                                        src=\"https:\/\/www-img-cc.s3.amazonaws.com\/inmuebles\/images\/3558291\/dca176426946134_plana.jpeg\"\n                                        alt=\"Apartamento\"\n                                        onerror=\"this.src='https:\/\/www.ciencuadras.com\/sources\/images\/result\/no-photo-property.png'\"\n                                    \/>\n                                <\/div>\n                                <div class=\"card-info\">\n                                    <div class=\"card-price\">\n                                        <span>Valor de compra: <\/span>                                        <br \/>\n                                        <span class=\"card-price-big\">$710.000.000 \n                                        <\/span>\n                                    <\/div>\n                                    <div class=\"card-location\">\n                                        Apartamento en Venta                                    <\/div>\n                                    <div class=\"card-direction\">\n                                        <div class=\"card-target\">\n                                            <em class=\"fas fa-map-marker-alt\"><\/em>\n                                            <span class=\"city\"> Sabaneta<\/span>\n                                            <span>&nbsp;\/&nbsp;<\/span>\n                                            <span class=\"neighborhood\"> Lagos De La Doctora<\/span>\n                                        <\/div>\n                                    <\/div>\n                                    <div class=\"specs\">\n                                        <div class=\"specs-data area\"><span class=\"span-data\">98 m2<\/span><\/div>\n                                        <div class=\"specs-data rooms\"><span class=\"span-data\">Habit. 2<\/span><\/div><div class=\"specs-data baths\"><span class=\"span-data\">Ba\u00f1os 3<\/span><\/div><div class=\"specs-data garages\"><span class=\"span-data\">Garaje 1<\/span><\/div>                                        \n                                        \n                                        \n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        <\/div>\n                    \n                   \n\t\t\t\n                                <div data-history=\"3\" class=\"swiper-slide\" >\n                            <a class=\"card\"  href=\"\/inmueble\/apartamento-en-venta-en-santa-ana-sabaneta-3029872\" target=\"_blank\">\n                                <div class=\"card-image\">\n                                    <img decoding=\"async\" class=\"img-inmueble\"  \n                                        src=\"https:\/\/www-img-cc.s3.amazonaws.com\/inmuebles\/images\/3029872\/c174066652149_plana.jpeg\"\n                                        alt=\"Apartamento\"\n                                        onerror=\"this.src='https:\/\/www.ciencuadras.com\/sources\/images\/result\/no-photo-property.png'\"\n                                    \/>\n                                <\/div>\n                                <div class=\"card-info\">\n                                    <div class=\"card-price\">\n                                        <span>Valor de compra: <\/span>                                        <br \/>\n                                        <span class=\"card-price-big\">$410.000.000 \n                                        <\/span>\n                                    <\/div>\n                                    <div class=\"card-location\">\n                                        Apartamento en Venta                                    <\/div>\n                                    <div class=\"card-direction\">\n                                        <div class=\"card-target\">\n                                            <em class=\"fas fa-map-marker-alt\"><\/em>\n                                            <span class=\"city\"> Sabaneta<\/span>\n                                            <span>&nbsp;\/&nbsp;<\/span>\n                                            <span class=\"neighborhood\"> Santa Ana<\/span>\n                                        <\/div>\n                                    <\/div>\n                                    <div class=\"specs\">\n                                        <div class=\"specs-data area\"><span class=\"span-data\">109 m2<\/span><\/div>\n                                        <div class=\"specs-data rooms\"><span class=\"span-data\">Habit. 4<\/span><\/div><div class=\"specs-data baths\"><span class=\"span-data\">Ba\u00f1os 3<\/span><\/div><div class=\"specs-data garages\"><span class=\"span-data\">Garaje 1<\/span><\/div>                                        \n                                        \n                                        \n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        <\/div>\n                    \n                   \n\t\t\t\n                                <div data-history=\"4\" class=\"swiper-slide\" >\n                            <a class=\"card\"  href=\"\/inmueble\/apartamento-en-venta-en-entre-amigos-sabaneta-3051172\" target=\"_blank\">\n                                <div class=\"card-image\">\n                                    <img decoding=\"async\" class=\"img-inmueble\"  \n                                        src=\"https:\/\/www-img-cc.s3.amazonaws.com\/inmuebles\/images\/3051172\/bcf176427601050_plana.jpeg\"\n                                        alt=\"Apartamento\"\n                                        onerror=\"this.src='https:\/\/www.ciencuadras.com\/sources\/images\/result\/no-photo-property.png'\"\n                                    \/>\n                                <\/div>\n                                <div class=\"card-info\">\n                                    <div class=\"card-price\">\n                                        <span>Valor de compra: <\/span>                                        <br \/>\n                                        <span class=\"card-price-big\">$680.000.000 \n                                        <\/span>\n                                    <\/div>\n                                    <div class=\"card-location\">\n                                        Apartamento en Venta                                    <\/div>\n                                    <div class=\"card-direction\">\n                                        <div class=\"card-target\">\n                                            <em class=\"fas fa-map-marker-alt\"><\/em>\n                                            <span class=\"city\"> Sabaneta<\/span>\n                                            <span>&nbsp;\/&nbsp;<\/span>\n                                            <span class=\"neighborhood\"> ENTRE AMIGOS<\/span>\n                                        <\/div>\n                                    <\/div>\n                                    <div class=\"specs\">\n                                        <div class=\"specs-data area\"><span class=\"span-data\">119 m2<\/span><\/div>\n                                        <div class=\"specs-data rooms\"><span class=\"span-data\">Habit. 3<\/span><\/div><div class=\"specs-data baths\"><span class=\"span-data\">Ba\u00f1os 3<\/span><\/div><div class=\"specs-data garages\"><span class=\"span-data\">Garaje 1<\/span><\/div>                                        \n                                        \n                                        \n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        <\/div>\n                    \n                   \n\t\t\t\n                                <div data-history=\"5\" class=\"swiper-slide\" >\n                            <a class=\"card\"  href=\"\/inmueble\/apartamento-en-venta-en-balcones-de-la-holanda-sabaneta-3316234\" target=\"_blank\">\n                                <div class=\"card-image\">\n                                    <img decoding=\"async\" class=\"img-inmueble\"  \n                                        src=\"https:\/\/www-img-cc.s3.amazonaws.com\/inmuebles\/images\/3316234\/faf_17453523445_plana.jpeg\"\n                                        alt=\"Apartamento\"\n                                        onerror=\"this.src='https:\/\/www.ciencuadras.com\/sources\/images\/result\/no-photo-property.png'\"\n                                    \/>\n                                <\/div>\n                                <div class=\"card-info\">\n                                    <div class=\"card-price\">\n                                        <span>Valor de compra: <\/span>                                        <br \/>\n                                        <span class=\"card-price-big\">$420.000.000 \n                                        <\/span>\n                                    <\/div>\n                                    <div class=\"card-location\">\n                                        Apartamento en Venta                                    <\/div>\n                                    <div class=\"card-direction\">\n                                        <div class=\"card-target\">\n                                            <em class=\"fas fa-map-marker-alt\"><\/em>\n                                            <span class=\"city\"> Sabaneta<\/span>\n                                            <span>&nbsp;\/&nbsp;<\/span>\n                                            <span class=\"neighborhood\"> Balcones De La Holanda<\/span>\n                                        <\/div>\n                                    <\/div>\n                                    <div class=\"specs\">\n                                        <div class=\"specs-data area\"><span class=\"span-data\">69 m2<\/span><\/div>\n                                        <div class=\"specs-data rooms\"><span class=\"span-data\">Habit. 3<\/span><\/div><div class=\"specs-data baths\"><span class=\"span-data\">Ba\u00f1os 2<\/span><\/div><div class=\"specs-data garages\"><span class=\"span-data\">Garaje 2<\/span><\/div>                                        \n                                        \n                                        \n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        <\/div>\n                    \n                   \n\t\t\t\n                                <div data-history=\"6\" class=\"swiper-slide\" >\n                            <a class=\"card\"  href=\"\/inmueble\/apartamento-en-venta-en-santa-ana-sabaneta-3480710\" target=\"_blank\">\n                                <div class=\"card-image\">\n                                    <img decoding=\"async\" class=\"img-inmueble\"  \n                                        src=\"https:\/\/www-img-cc.s3.amazonaws.com\/inmuebles\/images\/3480710\/dffdafc175855872189_plana.jpeg\"\n                                        alt=\"Apartamento\"\n                                        onerror=\"this.src='https:\/\/www.ciencuadras.com\/sources\/images\/result\/no-photo-property.png'\"\n                                    \/>\n                                <\/div>\n                                <div class=\"card-info\">\n                                    <div class=\"card-price\">\n                                        <span>Valor de compra: <\/span>                                        <br \/>\n                                        <span class=\"card-price-big\">$455.000.000 \n                                        <\/span>\n                                    <\/div>\n                                    <div class=\"card-location\">\n                                        Apartamento en Venta                                    <\/div>\n                                    <div class=\"card-direction\">\n                                        <div class=\"card-target\">\n                                            <em class=\"fas fa-map-marker-alt\"><\/em>\n                                            <span class=\"city\"> Sabaneta<\/span>\n                                            <span>&nbsp;\/&nbsp;<\/span>\n                                            <span class=\"neighborhood\"> Santa Ana<\/span>\n                                        <\/div>\n                                    <\/div>\n                                    <div class=\"specs\">\n                                        <div class=\"specs-data area\"><span class=\"span-data\">85 m2<\/span><\/div>\n                                        <div class=\"specs-data rooms\"><span class=\"span-data\">Habit. 3<\/span><\/div><div class=\"specs-data baths\"><span class=\"span-data\">Ba\u00f1os 2<\/span><\/div><div class=\"specs-data garages\"><span class=\"span-data\">Garaje 1<\/span><\/div>                                        \n                                        \n                                        \n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        <\/div>\n                    \n                   \n\t\t\t\n                                <div data-history=\"7\" class=\"swiper-slide\" >\n                            <a class=\"card\"  href=\"\/inmueble\/apartamento-en-venta-en-paso-ancho-sabaneta-3573724\" target=\"_blank\">\n                                <div class=\"card-image\">\n                                    <img decoding=\"async\" class=\"img-inmueble\"  \n                                        src=\"https:\/\/www-img-cc.s3.amazonaws.com\/inmuebles\/images\/3573724\/cbda176557544372_plana.jpeg\"\n                                        alt=\"Apartamento\"\n                                        onerror=\"this.src='https:\/\/www.ciencuadras.com\/sources\/images\/result\/no-photo-property.png'\"\n                                    \/>\n                                <\/div>\n                                <div class=\"card-info\">\n                                    <div class=\"card-price\">\n                                        <span>Valor de compra: <\/span>                                        <br \/>\n                                        <span class=\"card-price-big\">$520.000.000 \n                                        <\/span>\n                                    <\/div>\n                                    <div class=\"card-location\">\n                                        Apartamento en Venta                                    <\/div>\n                                    <div class=\"card-direction\">\n                                        <div class=\"card-target\">\n                                            <em class=\"fas fa-map-marker-alt\"><\/em>\n                                            <span class=\"city\"> Sabaneta<\/span>\n                                            <span>&nbsp;\/&nbsp;<\/span>\n                                            <span class=\"neighborhood\"> Paso Ancho<\/span>\n                                        <\/div>\n                                    <\/div>\n                                    <div class=\"specs\">\n                                        <div class=\"specs-data area\"><span class=\"span-data\">85 m2<\/span><\/div>\n                                        <div class=\"specs-data rooms\"><span class=\"span-data\">Habit. 3<\/span><\/div><div class=\"specs-data baths\"><span class=\"span-data\">Ba\u00f1os 2<\/span><\/div>                                        \n                                        \n                                        \n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        <\/div>\n                    \n                   \n\t\t\t\n                                <div data-history=\"8\" class=\"swiper-slide\" >\n                            <a class=\"card\"  href=\"\/inmueble\/apartamento-en-venta-en-sabaneta-sabaneta-2899338\" target=\"_blank\">\n                                <div class=\"card-image\">\n                                    <img decoding=\"async\" class=\"img-inmueble\"  \n                                        src=\"https:\/\/www-img-cc.s3.amazonaws.com\/inmuebles\/images\/2899338\/ter-170594508215_plana.jpeg\"\n                                        alt=\"Apartamento\"\n                                        onerror=\"this.src='https:\/\/www.ciencuadras.com\/sources\/images\/result\/no-photo-property.png'\"\n                                    \/>\n                                <\/div>\n                                <div class=\"card-info\">\n                                    <div class=\"card-price\">\n                                        <span>Valor de compra: <\/span>                                        <br \/>\n                                        <span class=\"card-price-big\">$410.000.000 \n                                        <\/span>\n                                    <\/div>\n                                    <div class=\"card-location\">\n                                        Apartamento en Venta                                    <\/div>\n                                    <div class=\"card-direction\">\n                                        <div class=\"card-target\">\n                                            <em class=\"fas fa-map-marker-alt\"><\/em>\n                                            <span class=\"city\"> Sabaneta<\/span>\n                                            <span>&nbsp;\/&nbsp;<\/span>\n                                            <span class=\"neighborhood\"> SABANETA<\/span>\n                                        <\/div>\n                                    <\/div>\n                                    <div class=\"specs\">\n                                        <div class=\"specs-data area\"><span class=\"span-data\">74.0 m2<\/span><\/div>\n                                        <div class=\"specs-data rooms\"><span class=\"span-data\">Habit. 3<\/span><\/div><div class=\"specs-data baths\"><span class=\"span-data\">Ba\u00f1os 2<\/span><\/div><div class=\"specs-data garages\"><span class=\"span-data\">Garaje 2<\/span><\/div>                                        \n                                        \n                                        \n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        <\/div>\n                    \n                   \n\t\t\t\n                                <div data-history=\"9\" class=\"swiper-slide\" >\n                            <a class=\"card\"  href=\"\/inmueble\/apartamento-en-venta-en-vereda-la-doctora-sabaneta-3115628\" target=\"_blank\">\n                                <div class=\"card-image\">\n                                    <img decoding=\"async\" class=\"img-inmueble\"  \n                                        src=\"https:\/\/www-img-cc.s3.amazonaws.com\/inmuebles\/images\/3115628\/LHArgCRpfMBtUSJjQroqv_uiOrtlCtQYuL_AolWujKwcdLD_jbuzifdqEWhOxStiGbNzwm_B_fSNiTSIEGSSqZCyR172865961426_plana.jpeg\"\n                                        alt=\"Apartamento\"\n                                        onerror=\"this.src='https:\/\/www.ciencuadras.com\/sources\/images\/result\/no-photo-property.png'\"\n                                    \/>\n                                <\/div>\n                                <div class=\"card-info\">\n                                    <div class=\"card-price\">\n                                        <span>Valor de compra: <\/span>                                        <br \/>\n                                        <span class=\"card-price-big\">$495.000.000 \n                                        <\/span>\n                                    <\/div>\n                                    <div class=\"card-location\">\n                                        Apartamento en Venta                                    <\/div>\n                                    <div class=\"card-direction\">\n                                        <div class=\"card-target\">\n                                            <em class=\"fas fa-map-marker-alt\"><\/em>\n                                            <span class=\"city\"> Sabaneta<\/span>\n                                            <span>&nbsp;\/&nbsp;<\/span>\n                                            <span class=\"neighborhood\"> Vereda La Doctora<\/span>\n                                        <\/div>\n                                    <\/div>\n                                    <div class=\"specs\">\n                                        <div class=\"specs-data area\"><span class=\"span-data\">79 m2<\/span><\/div>\n                                        <div class=\"specs-data rooms\"><span class=\"span-data\">Habit. 3<\/span><\/div><div class=\"specs-data baths\"><span class=\"span-data\">Ba\u00f1os 2<\/span><\/div><div class=\"specs-data garages\"><span class=\"span-data\">Garaje 1<\/span><\/div>                                        \n                                        \n                                        \n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        <\/div>\n                    \n                   \n\t\t\t\n                      \n                         <\/div>\n                    <\/div>\n                <div class=\"swiper-button-next next-swiper-id-c7f6307\"><\/div>\n                <div class=\"swiper-pagination  swiper-pagination-id-c7f6307\"><\/div>\n            <\/div>\n            <div class=\"container-button\">\n                <a href=\"\/venta\/sabaneta\/apartamento\" target=\"_blank\">\n                    <button class=\"slider-button\">Ver todos<\/button>\n                <\/a>\n\t\t    <\/div>\n\n            <script>\n                    idSwiper= 'c7f6307';\n                    window['swiperId'+idSwiper] =new Swiper(`.swiper-id-${idSwiper}`, {\n                    spaceBetween: 10,\n                    slidesPerView: 1,\n                    slidesPerGroup: 1,\n                    width:270,\n                    centeredSlides:true,\n                    rewind:true,\n                    breakpointsBase:`.container-id-${idSwiper}`,\n                    navigation: {\n                        nextEl: `.next-swiper-id-${idSwiper}`,\n                        prevEl: `.prev-swiper-id-${idSwiper}`,\n                    },\n                    pagination: {\n                        el: `.swiper-pagination-id-${idSwiper}`,\n                    },\n                    preloadImages: false,\n                    breakpoints: {\n                        600: {\n                            slidesPerView: 2,\n                            spaceBetween: 10,\n                            slidesPerGroup: 2,\n                            width:550,\n                            centeredSlidesBounds: true,\n                            centeredSlides:false,\n                        },\n                        900: {\n                            slidesPerView: 3,\n                            spaceBetween: 10,\n                            slidesPerGroup: 3,\n                            width:830,\n                            centeredSlidesBounds: true,\n                            centeredSlides:false,\n                        },\n                        1200: {\n                            slidesPerView: 4,\n                            spaceBetween: 12,\n                            slidesPerGroup: 4,\n                            width:1110,\n                            centeredSlidesBounds: true,\n                            centeredSlides:false,\n                        },\n                    },\n                });\n            <\/script>\n\n            \n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1df084c elementor-widget elementor-widget-heading\" data-id=\"1df084c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00a1Descubre m\u00e1s!<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4d0e95 e-con-full e-flex e-con e-child\" data-id=\"a4d0e95\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de2497d elementor-widget elementor-widget-html\" data-id=\"de2497d\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<blockquote class=\"instagram-media\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/reel\/DNZYjQNso3F\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/reel\/DNZYjQNso3F\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/reel\/DNZYjQNso3F\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\">A post shared by Ciencuadras | Bienes Ra\u00edces (@ciencuadras)<\/a><\/p><\/div><\/blockquote>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56643c4 elementor-widget elementor-widget-heading\" data-id=\"56643c4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Datos que debes conocer<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8b06cc elementor-widget elementor-widget-n-accordion\" data-id=\"d8b06cc\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2270\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-2270\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Datos que debes conocer <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2270\" class=\"elementor-element elementor-element-b359f27 e-con-full e-flex e-con e-child\" data-id=\"b359f27\" data-element_type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2270\" class=\"elementor-element elementor-element-9596277 e-flex e-con-boxed e-con e-child\" data-id=\"9596277\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a506d1d elementor-widget elementor-widget-text-editor\" data-id=\"a506d1d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Este sector es percibido como uno de los m\u00e1s seguros y tranquilos del municipio. Debido a su topograf\u00eda, la mayor\u00eda de los proyectos residenciales cuentan con balcones amplios y zonas sociales orientadas al descanso. Es un mercado din\u00e1mico para el <\/span><b>arrendamiento de larga estancia<\/b><span style=\"font-weight: 400;\">, especialmente para personas que trabajan de forma remota y valoran el silencio y la calidad del aire, lo que representa una oportunidad s\u00f3lida para inversores inmobiliarios.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2271\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2271\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Transporte  <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2271\" class=\"elementor-element elementor-element-6cf3053 e-con-full e-flex e-con e-child\" data-id=\"6cf3053\" data-element_type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2271\" class=\"elementor-element elementor-element-82b56a8 e-flex e-con-boxed e-con e-child\" data-id=\"82b56a8\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58f9376 elementor-widget elementor-widget-text-editor\" data-id=\"58f9376\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El acceso al transporte p\u00fablico es eficiente gracias a las rutas integradas del <\/span><b>Metro de Medell\u00edn<\/b><span style=\"font-weight: 400;\">, que conectan el barrio directamente con la <\/span><b>Estaci\u00f3n Sabaneta<\/b><span style=\"font-weight: 400;\"> y la <\/span><b>Estaci\u00f3n Itag\u00fc\u00ed<\/b><span style=\"font-weight: 400;\">. Adicionalmente, cuenta con rutas de buses circulares internas que facilitan el traslado hacia el Parque Principal. Para quienes utilizan transporte particular, la v\u00eda principal est\u00e1 pavimentada y se\u00f1alizada, aunque presenta pendientes pronunciadas propias de su ubicaci\u00f3n en la ladera.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2272\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2272\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> En La Doctora, Ciencuadras cuadra todo <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2272\" class=\"elementor-element elementor-element-887bdb9 e-con-full e-flex e-con e-child\" data-id=\"887bdb9\" data-element_type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2272\" class=\"elementor-element elementor-element-2d0b61e e-flex e-con-boxed e-con e-child\" data-id=\"2d0b61e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28ea348 elementor-widget elementor-widget-text-editor\" data-id=\"28ea348\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Te invitamos a explorar las opciones de apartamentos y casas disponibles en el sector de La Doctora. Encuentra el inmueble que mejor se adapte a tus necesidades de inversi\u00f3n o vivienda dentro de nuestro portal.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f114ad elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"6f114ad\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"130182\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"6f114ad\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Gu\u00eda de Barrio La Doctora Sabaneta Antioquia\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"130182\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNombre\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nombre\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCorreo\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Correo\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tComentario\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Escribe aqu\u00ed...\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75d19d7 elementor-widget elementor-widget-html\" data-id=\"75d19d7\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<table cellpadding='0' cellspacing='0' align='center' style='width: 100%'><tr style='text-align: center; font-family: Open Sans, sans-serif;'><td style='padding-bottom: 24px; color: #29292a; font-size: 18px; font-weight: 600'>\u00bfQu\u00e9 tan \u00fatil le pareci\u00f3 este contenido?<\/td><\/tr><tr style='text-align: center;'><td><table cellpadding='0' cellspacing='0' style='width: 100%; max-width: 400px; margin: auto'><tr><td><a style='text-decoration: none' href='https:\/\/survey.survicate.com\/2024c603f1ca0b80\/?pieza=130182_guia_de_barrio_la_doctora|Gu\u00edas|Gu\u00eda de barrios en Medell\u00edn&aid=2533768' target='_blank' rel='nofollow'> <img style='width: 32px; height: 32px' src='https:\/\/image.experienciasbolivar.segurosbolivar.com\/lib\/fe3511747364047b751475\/m\/1\/a2945bbd-60a9-43cb-b225-78bf5e055db5.png' > <\/a><\/td><td><a style='text-decoration: none' href='https:\/\/survey.survicate.com\/2024c603f1ca0b80\/?pieza=130182_guia_de_barrio_la_doctora|Gu\u00edas|Gu\u00eda de barrios en Medell\u00edn&aid=2533769' target='_blank' rel='nofollow'> <img style='width: 32px; height: 32px' src='https:\/\/image.experienciasbolivar.segurosbolivar.com\/lib\/fe3511747364047b751475\/m\/1\/161006d2-a309-4148-a578-df40c5152496.png' > <\/a><\/td><td><a style='text-decoration: none' href='https:\/\/survey.survicate.com\/2024c603f1ca0b80\/?pieza=130182_guia_de_barrio_la_doctora|Gu\u00edas|Gu\u00eda de barrios en Medell\u00edn&aid=2533770' target='_blank' rel='nofollow'> <img style='width: 32px; height: 32px' src='https:\/\/image.experienciasbolivar.segurosbolivar.com\/lib\/fe3511747364047b751475\/m\/1\/ba2c4c82-1c2c-4bcb-b894-20f6776af736.png' > <\/a><\/td><td><a style='text-decoration: none' href='https:\/\/survey.survicate.com\/2024c603f1ca0b80\/?pieza=130182_guia_de_barrio_la_doctora|Gu\u00edas|Gu\u00eda de barrios en Medell\u00edn&aid=2533771' target='_blank' rel='nofollow'> <img style='width: 32px; height: 32px' src='https:\/\/image.experienciasbolivar.segurosbolivar.com\/lib\/fe3511747364047b751475\/m\/1\/52e25dc4-db06-43e1-ada3-a13cc6834b02.png' > <\/a><\/td><td><a style='text-decoration: none' href='https:\/\/survey.survicate.com\/2024c603f1ca0b80\/?pieza=130182_guia_de_barrio_la_doctora|Gu\u00edas|Gu\u00eda de barrios en Medell\u00edn&aid=2533772' target='_blank' rel='nofollow'> <img style='width: 32px; height: 32px' src='https:\/\/image.experienciasbolivar.segurosbolivar.com\/lib\/fe3511747364047b751475\/m\/1\/f125fd9c-b185-4d5b-8a2c-c67e5f69c93b.png' > <\/a><\/td><\/tr><\/table><\/td><\/tr><\/table>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b0e538b e-con-full e-flex e-con e-child\" data-id=\"b0e538b\" data-element_type=\"container\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;sticky&quot;:&quot;top&quot;,&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54dd7e3 elementor-widget elementor-widget-heading\" data-id=\"54dd7e3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La Doctora en el mapa<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7556f3 elementor-widget elementor-widget-html\" data-id=\"c7556f3\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d31735.998004506717!2d-75.62319626067158!3d6.130734127396623!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x8e4683f40805f071%3A0x7bd9b2291608bcbb!2sLa%20Doctora%2C%20Sabaneta%2C%20Antioquia!5e0!3m2!1ses!2sco!4v1772727465596!5m2!1ses!2sco\" width=\"600\" height=\"250\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-888b2d3 elementor-widget elementor-widget-heading\" data-id=\"888b2d3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inmuebles en La Doctora<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4039c10 elementor-widget__width-inherit elementor-align-justify newProjects elementor-widget elementor-widget-button\" data-id=\"4039c10\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ciencuadras.com\/proyectos-vivienda-nueva\/sabaneta\/la-doctora\/apartamento?utm_source=Autopauta&#038;utm_medium=Blog_enlace&#038;utm_campaign=BG_130182_guia_de_barrio_la_doctora\" target=\"_blank\" id=\"newProjects\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Proyectos nuevos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d33157 elementor-align-justify rentalProperties elementor-widget elementor-widget-button\" data-id=\"7d33157\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ciencuadras.com\/arriendo\/sabaneta\/la-doctora\/apartamento?utm_source=Autopauta&#038;utm_medium=Blog_enlace&#038;utm_campaign=BG_130182_guia_de_barrio_la_doctora\" target=\"_blank\" id=\"rentalProperties\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Propiedades en arriendo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afbad2e elementor-align-justify saleProperties elementor-widget elementor-widget-button\" data-id=\"afbad2e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.ciencuadras.com\/venta\/sabaneta\/la-doctora\/apartamento?utm_source=Autopauta&#038;utm_medium=Blog_enlace&#038;utm_campaign=BG_130182_guia_de_barrio_la_doctora\" target=\"_blank\" id=\"saleProperties\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Propiedades en venta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n","protected":false},"excerpt":{"rendered":"<p>La Doctora en cifras $643.177.882 Precio promedio venta $8.513.552 Precio promedio m2 3 Estrato La Doctora es un sector tradicionalmente rural que ha evolucionado hacia &hellip;<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gu\u00eda de Barrio La Doctora Sabaneta Antioquia<\/title>\n<meta name=\"description\" content=\"Conoce todo sobre el Barrio La Doctora Sabaneta Antioquia su historia e informaci\u00f3n del sector inmobiliario, encuentra apartamentos, casas y proyectos de vivienda\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ciencuadras.com\/blog\/guia-de-barrio-la-doctora-sabaneta-antioquia\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gu\u00eda de Barrio La Doctora Sabaneta Antioquia\" \/>\n<meta property=\"og:description\" content=\"Conoce todo sobre el Barrio La Doctora Sabaneta Antioquia su historia e informaci\u00f3n del sector inmobiliario, encuentra apartamentos, casas y proyectos de vivienda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ciencuadras.com\/blog\/guia-de-barrio-la-doctora-sabaneta-antioquia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ciencuadras\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T15:43:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ciencuadras.com\/blog\/wp-content\/uploads\/2026\/03\/1200x630_La-Doctora-1024x536.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ciencuadras\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"8 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#organization\",\"name\":\"Ciencuadras.com\",\"url\":\"https:\/\/www.ciencuadras.com\/blog\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/ciencuadras\/\",\"https:\/\/www.instagram.com\/ciencuadras\/\",\"https:\/\/co.linkedin.com\/company\/ciencuadras\",\"https:\/\/www.youtube.com\/channel\/UC_f830HP5dUy6OjBIbjtlAw\",\"https:\/\/twitter.com\/ciencuadras\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#logo\",\"inLanguage\":\"es-CO\",\"url\":\"\",\"caption\":\"Ciencuadras.com\"},\"image\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#website\",\"url\":\"https:\/\/www.ciencuadras.com\/blog\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.ciencuadras.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-CO\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/guia-de-barrio-la-doctora-sabaneta-antioquia#primaryimage\",\"inLanguage\":\"es-CO\",\"url\":\"https:\/\/www.ciencuadras.com\/blog\/wp-content\/uploads\/2026\/03\/1200x630_La-Doctora.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/guia-de-barrio-la-doctora-sabaneta-antioquia#webpage\",\"url\":\"https:\/\/www.ciencuadras.com\/blog\/guia-de-barrio-la-doctora-sabaneta-antioquia\",\"name\":\"Gu\\u00eda de Barrio La Doctora Sabaneta Antioquia\",\"isPartOf\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/guia-de-barrio-la-doctora-sabaneta-antioquia#primaryimage\"},\"datePublished\":\"2026-04-27T15:43:18+00:00\",\"dateModified\":\"2026-04-27T15:43:20+00:00\",\"description\":\"Conoce todo sobre el Barrio La Doctora Sabaneta Antioquia su historia e informaci\\u00f3n del sector inmobiliario, encuentra apartamentos, casas y proyectos de vivienda\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/guia-de-barrio-la-doctora-sabaneta-antioquia#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ciencuadras.com\/blog\/guia-de-barrio-la-doctora-sabaneta-antioquia\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/guia-de-barrio-la-doctora-sabaneta-antioquia#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\",\"url\":\"https:\/\/www.ciencuadras.com\/blog\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/guia-de-barrio-la-doctora-sabaneta-antioquia\",\"url\":\"https:\/\/www.ciencuadras.com\/blog\/guia-de-barrio-la-doctora-sabaneta-antioquia\",\"name\":\"La Doctora, un refugio campestre y exclusivo en Sabaneta\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/pages\/130182"}],"collection":[{"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/comments?post=130182"}],"version-history":[{"count":8,"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/pages\/130182\/revisions"}],"predecessor-version":[{"id":131407,"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/pages\/130182\/revisions\/131407"}],"wp:attachment":[{"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/media?parent=130182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}