{"id":121396,"date":"2024-04-25T17:04:56","date_gmt":"2024-04-25T22:04:56","guid":{"rendered":"https:\/\/www.ciencuadras.com\/blog\/?p=121396"},"modified":"2025-03-03T12:19:32","modified_gmt":"2025-03-03T17:19:32","slug":"cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral","status":"publish","type":"post","link":"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral","title":{"rendered":"Se avecina un cambio de tendencia en las condiciones del mercado inmobiliario"},"content":{"rendered":"\n<ul>\n<li><em>Las ventas de vivienda nueva caen 12% en el 1er trimestre de 2024 y las tasas de inter\u00e9s presentan una mejora aproximada de 2 puntos b\u00e1sicos, seg\u00fan el informe inmobiliario de ciencuadras.com<\/em><\/li>\n\n\n\n<li><em>Bogot\u00e1 (22,64%), Medell\u00edn (15,60%) y Barranquilla (8,14%) concentran la demanda de vivienda usada en el pa\u00eds.<\/em><\/li>\n\n\n\n<li><em>La mayor\u00eda de los seguros de hogar (70%) son adquiridos por personas con ingresos de 4 millones de pesos en adelante, de acuerdo con la plataforma Ciencuadras y Seguros Bol\u00edvar.<\/em><\/li>\n<\/ul>\n\n\n\n<p>El panorama inmobiliario en Colombia durante el primer trimestre de 2024 presenta desaf\u00edos significativos que requieren acci\u00f3n estrat\u00e9gica, como se evidencia en el <strong>1er informe trimestral de <\/strong><a href=\"https:\/\/www.ciencuadras.com\/?utm_source=Prensa&amp;utm_medium=Referral&amp;utm_campaign=BG_Comunicado_Informe_Anual_2023\"><strong>ciencuadras.com<\/strong><\/a> de 2024. El sector de la vivienda nueva sigue en una fase de desaceleraci\u00f3n: bajas ventas, altos desistimientos y mayores inventarios terminados. No obstante, \u201cnosotros vemos que <strong>viene un cambio de tendencia de las condiciones del mercado<\/strong>. Proyectamos una&nbsp; <strong>disminuci\u00f3n de las tasas de inter\u00e9s y un leve incremento en las ventas para el segundo semestre<\/strong>\u201d, explica Mauricio Torres Romero, gerente de Ciencuadras.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline\"><a class=\"wp-block-button__link has-white-background-color has-text-color has-background has-text-align-center wp-element-button\" href=\"https:\/\/www.ciencuadras.com\/blog\/wp-content\/uploads\/2024\/04\/I-Informe-Trimestral-2024-comprimido.pdf\" style=\"color:#026094\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>1er Informe Trimestral 2024<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ventas de vivienda nueva caen 12%<\/strong>, seg\u00fan 1er informe trimestral 2024<\/h2>\n\n\n\n<p>Si bien las ventas de vivienda nueva tuvieron un decrecimiento del <strong>12%<\/strong> en el primer trimestre del a\u00f1o, comparado con el mismo periodo de 2023, \u201c<strong>observamos una reactivaci\u00f3n del mercado, con ventas mucho m\u00e1s estables, y no tan desacelerado como en a\u00f1os anteriores, debido a la reducci\u00f3n de las tasas y otras acciones implementadas por los actores del sector\u201d<\/strong>, comenta Torres Romero. Una referencia de lo mencionado es el decrecimiento del mismo periodo entre 2022 y 2023, que fue mucho mayor, con una ca\u00edda del <strong>56%,<\/strong> como se ve en la siguiente gr\u00e1fica. Es decir, las ventas han venido subiendo con respecto a los m\u00ednimos hist\u00f3ricos, pero a\u00fan est\u00e1n bajas frente a los promedios de los \u00faltimos a\u00f1os.<\/p>\n\n\n\n<p><strong>Gr\u00e1fica 1. Ventas de proyectos VIS y No VIS (vivienda nueva)<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/LSXviLqwjLXFD_ewu7Ddi2qj_p3oyJqoUAZ3l51Iq4PxCLyMmsqXAH5h2HV3rfDlORYmoyl2xEdb83tHFy_GHjs2v-wprSgA3C2N0c21r1_zm-hLaijYKfKVEU29Q4mOkpkliZowL1gzUpP9RqcEjSI\" alt=\"\" style=\"aspect-ratio:1.0636942675159236;width:709px;height:auto\"\/><\/figure><\/div>\n\n\n<p><em>Fuente: La Galer\u00eda Inmobiliaria, informe Comportamiento de vivienda nueva &#8211; NIVEL NACIONAL I TRIMESTRE 2024<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Reducci\u00f3n de las tasas de inter\u00e9s versus ventas de vivienda nueva<\/strong><\/h2>\n\n\n\n<p>Para Mauricio Torres, <strong>es una buena noticia que las tasas de inter\u00e9s presenten actualmente una mejora de 2 puntos b\u00e1sicos<\/strong>, adem\u00e1s, de acuerdo con el informe trimestral del portal inmobiliario, se estima que <strong>seguir\u00e1n bajando en la misma medida a lo largo del a\u00f1o<\/strong>.&nbsp;<\/p>\n\n\n\n<p>\u201cSin embargo, esto no es un efecto que sea inmediato, por eso aunque disminuyen las tasas, no vemos un incremento en la venta de vivienda nueva\u201d, aclara. A lo anterior se suma que <strong>la compra de un inmueble, no depende solo del valor de las tasas de inter\u00e9s, sino que hay varios factores involucrados<\/strong>, como contar con el cr\u00e9dito hipotecario y la cuota inicial, que se puede completar con subsidios y\/o ahorros.&nbsp;<\/p>\n\n\n\n<p><strong>Gr\u00e1fica 2. Comportamiento de cr\u00e9ditos hipotecarios<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/Mhqs0AYGKbapEdwuAL54r9Ffl56NUYP04UsYPiiML8F3EqF1SwsoLGgxsONRY1x4RY8AbGRhw7msrGtGGSbte9uwtZzeR50ZW5OukhLf4KPksVTf7PozTlit6V1cjQXlXu_ktHzv_l2Y8REc9jpFrKw\" alt=\"\"\/><\/figure>\n\n\n\n<p>Seg\u00fan el an\u00e1lisis del articulador inmobiliario, <a href=\"https:\/\/www.ciencuadras.com\/?utm_source=Prensa&amp;utm_medium=Referral&amp;utm_campaign=BG_Comunicado_Informe_Anual_2023\"><strong>ciencuadras.com<\/strong><\/a>, se espera que el esquema de preasignaci\u00f3n de los subsidios de Mi Casa Ya (MCY) favorezca el acceso a vivienda e impulse el cambio de tendencia. En la medida en que siga mejorando la capacidad adquisitiva en el pa\u00eds con incentivos como estos, las ventas ir\u00e1n creciendo.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ventas de usada y oferta de arriendo se concentra en Bogot\u00e1 y Medell\u00edn<\/strong><\/h2>\n\n\n\n<p>En el primer trimestre de 2024, la mayor\u00eda de las ventas de vivienda usada se realizaron en<strong> Bogot\u00e1 (22,64%), Medell\u00edn (15,60%) y Barranquilla (8,14%)<\/strong>. De forma particular, ciudades como Sabaneta tomaron fuerza en su participaci\u00f3n, respecto al a\u00f1o anterior y otras como Envigado, se mantienen fuertes en el ranking.<\/p>\n\n\n\n<p><strong>Gr\u00e1fica 3. Top de la demanda de inmuebles en venta por ciudades<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/2z5d4V3dFMsMfeB5dSprq2bY2vYa7CC9LTBbrFRDCwYai0GIonBcKjtLv4NVXxuldpA2iPBUa6--YlOrzHRZU63PJnceEXDkwd93_aEz6UPbt5PISmwFLfHOAjBp962f0Q0XNwsRxlYEEtB31m2PUUg\" alt=\"\"\/><\/figure>\n\n\n\n<p>De la misma manera que en a\u00f1os anteriores, Medell\u00edn y Bogot\u00e1 concentran la oferta de inmuebles en arriendo, con el <strong>36,81% <\/strong>y <strong>20,81% <\/strong>de la participaci\u00f3n, respectivamente. Sin embargo, su participaci\u00f3n disminuye en promedio 3 puntos porcentuales. Por su parte, Envigado, Itag\u00fc\u00ed, Bello y Sabaneta incrementaron su oferta en este inicio de 2024.<\/p>\n\n\n\n<p><strong>Gr\u00e1fica 4. Top de la oferta de inmuebles en arriendo por ciudades<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/SpyvCEL_Qosah_CLymczVJsa1MQDDdr1eRiLsmW3DsbxXXoqdDLovAk3p11rhvWDjrgjkROjlZOwqUNigCmuLZBeaieEbErdnb-PemmcRv0PoyVRA0LUEF-A8jvHcDb2MaNdIkdog1-JWpdwnkFhz_0\" alt=\"\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Compra de vivienda y la adquisici\u00f3n de un seguro de hogar<\/strong><\/h2>\n\n\n\n<p>La adquisici\u00f3n del seguro de hogar est\u00e1 asociada a los clientes que han comprado vivienda en los \u00faltimos a\u00f1os. \u201cComo lo vemos en nuestro informe, la mayor\u00eda de los seguros de hogar (<strong>70%<\/strong>) son adquiridos por personas en el segmento de ingresos de 4 millones de pesos hacia arriba, por lo que podemos concluir que <strong>es un seguro atado principalmente a la compra de vivienda No VIS\u201d<\/strong>, advierte Mauricio Torres Romero.&nbsp;<\/p>\n\n\n\n<p><strong>Gr\u00e1fica 5. Perfil del cliente que adquiere un Seguro de Hogar con Seguros Bol\u00edvar<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-us.googleusercontent.com\/ytHG3CMzrSBwsgieVQkEYtoJInkQVNrNpjceUjDUBAU0x_B1MvBz1gYVsRRuy4-AyMMEO4TNN6DANKIVkLqA5hs6eokFO9JkVBDLelJevAEh3DdGQq4dhXdmWfNMB5NcEKHAuu6FzDjVBYgFeWSfZjk\" alt=\"\"\/><\/figure>\n\n\n\n<p><em>Esta informaci\u00f3n hace referencia al perfil del cliente que cuenta con el<\/em><\/p>\n\n\n\n<p><em>Seguro de Hogar de Seguros Bol\u00edvar, a corte del mes de febrero de 2024.<\/em><\/p>\n\n\n\n<p>El <strong>Seguro de Hogar<\/strong> de <strong>Seguros Bol\u00edvar<\/strong> cada vez cobra m\u00e1s relevancia entre los colombianos, pues protege el patrimonio de las personas, e incluso, puede ser adquirido exclusivamente para salvaguardar los contenidos internos de una vivienda. De esta forma, en caso de cualquier eventualidad, de inmediato se cuenta con la protecci\u00f3n necesaria para no perder los activos propios.<\/p>\n\n\n\n<p><strong>Aunque los cr\u00e9ditos hipotecarios cuentan con un seguro obligatorio, es importante tener en cuenta las diferencias de estos dos seguros<\/strong>, ya que el obligatorio asociado al cr\u00e9dito, se ocupa particularmente de la deuda y si bien cuenta con algunas asistencias adicionales, no se encarga de la cobertura total de los activos.&nbsp;<\/p>\n\n\n\n<p><strong>Ciencuadras socializa este informe, que est\u00e1 basado en datos propios y respaldados por organizaciones aliadas como Banco Davivienda, La Galer\u00eda Inmobiliaria, El Libertador y Seguros Bol\u00edvar,&nbsp; con el objeto de dar a conocer el panorama del mercado inmobiliario del pa\u00eds.<\/strong><br><strong>Mayor informaci\u00f3n: <a href=\"https:\/\/www.ciencuadras.com\/blog\/wp-content\/uploads\/2024\/04\/I-Informe-Trimestral-2024-comprimido.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">1er Informe Trimestral del sector inmobiliario en Colombia 2024<\/a><\/strong><\/p>\n\n\n\n<table cellpadding='0' cellspacing='0' align='center' style='width: 100%'><tr style='text-align: center; font-family: Open Sans, sans-serif;'><td style='padding-bottom: 24px; color: #29292a; font-size: 18px; font-weight: 600'>\u00bfQu\u00e9 tan \u00fatil te pareci\u00f3 este contenido?<\/td><\/tr><tr style='text-align: center;'><td><table cellpadding='0' cellspacing='0' style='width: 100%; max-width: 400px; margin: auto'><tr><td><a style='text-decoration: none' href='https:\/\/survey.survicate.com\/2024c603f1ca0b80\/?pieza=121396_Cambio_de_tendencia_en_las_condiciones_del_mercado_inmobiliario|Informes|Sala de prensa&#038;aid=2533768' target='_blank' rel=\"nofollow noopener\"> <img style='width: 32px; height: 32px' src='https:\/\/image.experienciasbolivar.segurosbolivar.com\/lib\/fe3511747364047b751475\/m\/1\/a2945bbd-60a9-43cb-b225-78bf5e055db5.png' > <\/a><\/td><td><a style='text-decoration: none' href='https:\/\/survey.survicate.com\/2024c603f1ca0b80\/?pieza=121396_Cambio_de_tendencia_en_las_condiciones_del_mercado_inmobiliario|Informes|Sala de prensa&#038;aid=2533769' target='_blank' rel=\"nofollow noopener\"> <img style='width: 32px; height: 32px' src='https:\/\/image.experienciasbolivar.segurosbolivar.com\/lib\/fe3511747364047b751475\/m\/1\/161006d2-a309-4148-a578-df40c5152496.png' > <\/a><\/td><td><a style='text-decoration: none' href='https:\/\/survey.survicate.com\/2024c603f1ca0b80\/?pieza=121396_Cambio_de_tendencia_en_las_condiciones_del_mercado_inmobiliario|Informes|Sala de prensa&#038;aid=2533770' target='_blank' rel=\"nofollow noopener\"> <img style='width: 32px; height: 32px' src='https:\/\/image.experienciasbolivar.segurosbolivar.com\/lib\/fe3511747364047b751475\/m\/1\/ba2c4c82-1c2c-4bcb-b894-20f6776af736.png' > <\/a><\/td><td><a style='text-decoration: none' href='https:\/\/survey.survicate.com\/2024c603f1ca0b80\/?pieza=121396_Cambio_de_tendencia_en_las_condiciones_del_mercado_inmobiliario|Informes|Sala de prensa&#038;aid=2533771' target='_blank' rel=\"nofollow noopener\"> <img style='width: 32px; height: 32px' src='https:\/\/image.experienciasbolivar.segurosbolivar.com\/lib\/fe3511747364047b751475\/m\/1\/52e25dc4-db06-43e1-ada3-a13cc6834b02.png' > <\/a><\/td><td><a style='text-decoration: none' href='https:\/\/survey.survicate.com\/2024c603f1ca0b80\/?pieza=121396_Cambio_de_tendencia_en_las_condiciones_del_mercado_inmobiliario|Informes|Sala de prensa&#038;aid=2533772' target='_blank' rel=\"nofollow noopener\"> <img style='width: 32px; height: 32px' src='https:\/\/image.experienciasbolivar.segurosbolivar.com\/lib\/fe3511747364047b751475\/m\/1\/f125fd9c-b185-4d5b-8a2c-c67e5f69c93b.png' > <\/a><\/td><\/tr><\/table><\/td><\/tr><\/table>\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Las ventas de vivienda nueva caen 12%, seg\u00fan nuestro 1er informe trimestral 2024. Descubre m\u00e1s de la actualidad del sector, aqu\u00ed.\ud83c\udfe1<\/p>\n","protected":false},"author":9,"featured_media":121397,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6097,6099,6054],"tags":[42,41,2656],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cambio en la tendencia del mercado inmobiliario 1er Informe Trimestral<\/title>\n<meta name=\"description\" content=\"Las ventas de vivienda nueva caen 12%, seg\u00fan nuestro 1er informe trimestral 2024. Descubre m\u00e1s de la actualidad del sector, aqu\u00ed.\ud83c\udfe1\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cambio en la tendencia del mercado inmobiliario 1er Informe Trimestral\" \/>\n<meta property=\"og:description\" content=\"Las ventas de vivienda nueva caen 12%, seg\u00fan nuestro 1er informe trimestral 2024. Descubre m\u00e1s de la actualidad del sector, aqu\u00ed.\ud83c\udfe1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ciencuadras\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ciencuadras\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-25T22:04:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-03T17:19:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ciencuadras.com\/blog\/wp-content\/uploads\/2024\/04\/Open_I-informe-trimestral-2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ciencuadras\" \/>\n<meta name=\"twitter:site\" content=\"@ciencuadras\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"7 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#organization\",\"name\":\"Ciencuadras.com\",\"url\":\"https:\/\/www.ciencuadras.com\/blog\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/ciencuadras\/\",\"https:\/\/www.instagram.com\/ciencuadras\/\",\"https:\/\/co.linkedin.com\/company\/ciencuadras\",\"https:\/\/www.youtube.com\/channel\/UC_f830HP5dUy6OjBIbjtlAw\",\"https:\/\/twitter.com\/ciencuadras\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#logo\",\"inLanguage\":\"es-CO\",\"url\":\"\",\"caption\":\"Ciencuadras.com\"},\"image\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#website\",\"url\":\"https:\/\/www.ciencuadras.com\/blog\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.ciencuadras.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-CO\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral#primaryimage\",\"inLanguage\":\"es-CO\",\"url\":\"https:\/\/www.ciencuadras.com\/blog\/wp-content\/uploads\/2024\/04\/Open_I-informe-trimestral-2024.jpg\",\"width\":700,\"height\":500,\"caption\":\"1er informe trimestral 2024\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral#webpage\",\"url\":\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral\",\"name\":\"Cambio en la tendencia del mercado inmobiliario 1er Informe Trimestral\",\"isPartOf\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral#primaryimage\"},\"datePublished\":\"2024-04-25T22:04:56+00:00\",\"dateModified\":\"2025-03-03T17:19:32+00:00\",\"description\":\"Las ventas de vivienda nueva caen 12%, seg\\u00fan nuestro 1er informe trimestral 2024. Descubre m\\u00e1s de la actualidad del sector, aqu\\u00ed.\\ud83c\\udfe1\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\",\"url\":\"https:\/\/www.ciencuadras.com\/blog\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral\",\"url\":\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral\",\"name\":\"Se avecina un cambio de tendencia en las condiciones del mercado inmobiliario\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral#webpage\"},\"author\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#\/schema\/person\/cc0b32db93618f32995212860cf644f8\"},\"headline\":\"Se avecina un cambio de tendencia en las condiciones del mercado inmobiliario\",\"datePublished\":\"2024-04-25T22:04:56+00:00\",\"dateModified\":\"2025-03-03T17:19:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral#webpage\"},\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral#primaryimage\"},\"keywords\":\"Mercado inmobiliario,Sector inmobiliario,Tendencias inmobiliarias\",\"articleSection\":\"Evoluci\\u00f3n del mercado de vivienda,Informes del sector inmobiliario,Sala de prensa\",\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ciencuadras.com\/blog\/sala-de-prensa\/cambio-en-la-tendencia-del-mercado-inmobiliario-1er-informe-trimestral#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ciencuadras.com\/blog\/#\/schema\/person\/cc0b32db93618f32995212860cf644f8\",\"name\":\"Redacci\\u00f3n Ciencuadras\",\"description\":\"\\u00a1Hola! Soy el blog de ciencuadras.com, un portal inmobiliario del Grupo Bol\\u00edvar en el que encuentras casas, apartamentos, oficinas, fincas y m\\u00e1s inmuebles en arriendo y venta en toda Colombia. \\ud83d\\udc99Cuando me visitas, adem\\u00e1s de descubrir tu inmueble ideal, puedes estar al d\\u00eda con las noticias del sector inmobiliario y de la construcci\\u00f3n; aprender tips en decoraci\\u00f3n y organizaci\\u00f3n de espacios, y mucho m\\u00e1s.\",\"sameAs\":[\"https:\/\/www.ciencuadras.com\/\",\"https:\/\/www.facebook.com\/ciencuadras\/\",\"https:\/\/www.instagram.com\/ciencuadras\/\",\"https:\/\/www.linkedin.com\/company\/ciencuadras\/\",\"https:\/\/twitter.com\/ciencuadras\",\"https:\/\/www.youtube.com\/channel\/UC_f830HP5dUy6OjBIbjtlAw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/posts\/121396"}],"collection":[{"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/comments?post=121396"}],"version-history":[{"count":6,"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/posts\/121396\/revisions"}],"predecessor-version":[{"id":123479,"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/posts\/121396\/revisions\/123479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/media\/121397"}],"wp:attachment":[{"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/media?parent=121396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/categories?post=121396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ciencuadras.com\/blog\/wp-json\/wp\/v2\/tags?post=121396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}